{"id":2175,"date":"2022-02-25T19:04:01","date_gmt":"2022-02-25T18:04:01","guid":{"rendered":"https:\/\/bevercare.ch\/pagina-iniziale\/"},"modified":"2026-01-08T13:29:42","modified_gmt":"2026-01-08T12:29:42","slug":"pagina-iniziale","status":"publish","type":"page","link":"https:\/\/bevercare.ch\/it\/","title":{"rendered":"Pagina iniziale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2175\" class=\"elementor elementor-2175 elementor-25\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c333c8c e-flex e-con-boxed e-con e-parent\" data-id=\"c333c8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1119,&quot;url&quot;:&quot;https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1-scaled.jpg&quot;},{&quot;id&quot;:1121,&quot;url&quot;:&quot;https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/3-scaled.jpg&quot;},{&quot;id&quot;:1122,&quot;url&quot;:&quot;https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/4-scaled.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33ccc06 e-flex e-con-boxed e-con e-parent\" data-id=\"33ccc06\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8b14378 e-flex e-con-boxed e-con e-child\" data-id=\"8b14378\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-609b0c1 elementor-widget elementor-widget-heading\" data-id=\"609b0c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bever come ispirazione per l'armonia tra tradizione e scienza moderna.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ee7a3 elementor-widget elementor-widget-text-editor\" data-id=\"63ee7a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ispirati dalla bellezza mozzafiato delle Alpi svizzere e dalla purezza dell&#8217;aria salubre di montagna di Bever, i nostri prodotti per la cura del cavo orale e del corpo rappresentano la perfetta combinazione di tradizione, natura e scienza moderna. I nostri prodotti sono pensati per promuovere la tua salute e sostenere uno stile di vita sano e sostenibile. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dd7a95 e-flex e-con-boxed e-con e-child\" data-id=\"5dd7a95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cbda33 elementor-widget elementor-widget-heading\" data-id=\"8cbda33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Un'azienda a conduzione familiare<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53267e4 elementor-widget elementor-widget-text-editor\" data-id=\"53267e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In quanto azienda familiare con una visione condivisa, diamo particolare valore alla fiducia, alla coerenza e alla qualit\u00e0. Ci appassiona commercializzare e vendere prodotti di alta qualit\u00e0 che creino un reale valore aggiunto per i nostri clienti. <\/p><p>Con una forte attenzione al mercato svizzero e joint venture strategiche in altri paesi europei come i Paesi Bassi, lavoriamo sia con marchi affermati che con nuovi arrivati innovativi &#8211; sempre con una visione chiara, una lungimiranza strategica e l&#8217;ambizione di offrire solo i prodotti migliori.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdada13 e-flex e-con-boxed e-con e-parent\" data-id=\"cdada13\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f4dab1 elementor-widget elementor-widget-image\" data-id=\"9f4dab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png\" class=\"attachment-large size-large wp-image-2178\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14f509a e-flex e-con-boxed e-con e-parent\" data-id=\"14f509a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6db15b6 e-con-full e-flex e-con e-child\" data-id=\"6db15b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1bb2c0 elementor-widget elementor-widget-heading\" data-id=\"f1bb2c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">I nostri marchi<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e41b6a3 elementor-widget elementor-widget-text-editor\" data-id=\"e41b6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Immergiti nel mondo di BeverCare e conosci i prodotti originali di REACH\u2122 The Original, l&#8217;igiene orale svizzera edel+white o i marchi K-Beauty Dr Belmeur e belif di LG.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac4990e elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"ac4990e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:0,&quot;speed&quot;:5000,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Marken Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/reach-logo_2-300x146-1.png\" alt=\"REACH logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/edelwhite_LOGO_400px.png\" alt=\"edel+white logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/images-2.png\" alt=\"Euthymol logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/unnamed_4e96f0bf-160f-4e4f-a5d9-53f167313439.jpg.webp\" alt=\"Dr. Belmeur logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/images-3.png\" alt=\"belif logo\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/08\/GengigelLogo-HA.jpg\" alt=\"GENGIGEL Hyaluronic Acid Hyalurons\u00e4ure Original Ricerfarma Italien Entz\u00fcndungen Mundraum\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 7\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/08\/megasmile_400px.jpg\" alt=\"megasmile_400px\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-847286d e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"847286d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c950ec4 e-con-full e-transform e-transform e-flex e-con e-child\" data-id=\"c950ec4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3.5,&quot;sizes&quot;:[]},&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;in-out&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:11,&quot;sizes&quot;:[]},&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:53,&quot;end&quot;:100}},&quot;animation&quot;:&quot;none&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-12,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3002622 elementor-widget elementor-widget-heading\" data-id=\"3002622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Cura del cavo orale<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d737236 elementor-widget elementor-widget-heading\" data-id=\"d737236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">REACH\u2122\nedel+white\nGENGIGEL\nEuthymol<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f16816 e-con-full e-transform e-transform e-flex e-con e-child\" data-id=\"9f16816\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2.8,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:10,&quot;end&quot;:75}},&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;in-out&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:11,&quot;sizes&quot;:[]},&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:53,&quot;end&quot;:100}},&quot;animation&quot;:&quot;none&quot;,&quot;_transform_rotateZ_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-3,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.05,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;_transform_rotateZ_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-855b9cf elementor-widget elementor-widget-heading\" data-id=\"855b9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Cura del corpo<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c92ae0 elementor-widget elementor-widget-heading\" data-id=\"3c92ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Dr Belmeur\nbelif<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47a3400 e-con-full e-transform e-flex e-con e-child\" data-id=\"47a3400\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3.9,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:15,&quot;end&quot;:86}},&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;in-out&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:11,&quot;sizes&quot;:[]},&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:53,&quot;end&quot;:100}},&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-6,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d788abd elementor-widget elementor-widget-heading\" data-id=\"d788abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">BeverCare<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-957785f elementor-widget elementor-widget-heading\" data-id=\"957785f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Soluzioni svizzere per l'autocura<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef7b182 e-flex e-con-boxed e-con e-parent\" data-id=\"ef7b182\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b47d3 elementor-widget elementor-widget-spacer\" data-id=\"d7b47d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bever come ispirazione per l&#8217;armonia tra tradizione e scienza moderna. Ispirati dalla bellezza mozzafiato delle Alpi svizzere e dalla purezza dell&#8217;aria salubre di montagna di Bever, i nostri prodotti per la cura del cavo orale e del corpo rappresentano la perfetta combinazione di tradizione, natura e scienza moderna. I nostri prodotti sono pensati per promuovere [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2175","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pagina iniziale - BeverCare<\/title>\n<meta name=\"description\" content=\"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bevercare.ch\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pagina iniziale - BeverCare\" \/>\n<meta property=\"og:description\" content=\"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bevercare.ch\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"BeverCare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T12:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/\",\"url\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/\",\"name\":\"Pagina iniziale - BeverCare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Sgraffito-150x150-1.png\",\"datePublished\":\"2022-02-25T18:04:01+00:00\",\"dateModified\":\"2026-01-08T12:29:42+00:00\",\"description\":\"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bevercare.ch\\\/it\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Sgraffito-150x150-1.png\",\"contentUrl\":\"https:\\\/\\\/bevercare.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Sgraffito-150x150-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pagina iniziale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/\",\"name\":\"BeverCare\",\"description\":\"Swiss Selfcare Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bevercare.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pagina iniziale - BeverCare","description":"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bevercare.ch\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Pagina iniziale - BeverCare","og_description":"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.","og_url":"https:\/\/bevercare.ch\/it\/","og_site_name":"BeverCare","article_modified_time":"2026-01-08T12:29:42+00:00","og_image":[{"width":150,"height":150,"url":"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bevercare.ch\/it\/","url":"https:\/\/bevercare.ch\/it\/","name":"Pagina iniziale - BeverCare","isPartOf":{"@id":"https:\/\/bevercare.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bevercare.ch\/it\/#primaryimage"},"image":{"@id":"https:\/\/bevercare.ch\/it\/#primaryimage"},"thumbnailUrl":"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png","datePublished":"2022-02-25T18:04:01+00:00","dateModified":"2026-01-08T12:29:42+00:00","description":"Bevercare Swiss Selfcare Solutions \u00e8 sinonimo di una gamma di straordinari marchi dentali e cosmetici e di prodotti di bellezza coreani.","breadcrumb":{"@id":"https:\/\/bevercare.ch\/it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bevercare.ch\/it\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bevercare.ch\/it\/#primaryimage","url":"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png","contentUrl":"https:\/\/bevercare.ch\/wp-content\/uploads\/2025\/01\/Sgraffito-150x150-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/bevercare.ch\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bevercare.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Pagina iniziale"}]},{"@type":"WebSite","@id":"https:\/\/bevercare.ch\/it\/#website","url":"https:\/\/bevercare.ch\/it\/","name":"BeverCare","description":"Swiss Selfcare Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bevercare.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/pages\/2175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/comments?post=2175"}],"version-history":[{"count":5,"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/pages\/2175\/revisions"}],"predecessor-version":[{"id":2536,"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/pages\/2175\/revisions\/2536"}],"wp:attachment":[{"href":"https:\/\/bevercare.ch\/it\/wp-json\/wp\/v2\/media?parent=2175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}